{"id":17430,"date":"2024-02-08T08:45:29","date_gmt":"2024-02-08T07:45:29","guid":{"rendered":"https:\/\/www.gaches.com\/?p=17430"},"modified":"2024-02-08T08:45:29","modified_gmt":"2024-02-08T07:45:29","slug":"expiris-expertise-globale-des-materiaux-traitements-de-surface-peintures-et-revetements","status":"publish","type":"post","link":"https:\/\/www.gaches.com\/nl\/expiris-expertise-globale-des-materiaux-traitements-de-surface-peintures-et-revetements\/","title":{"rendered":"[EXPIRIS] Laboratoire de rev\u00eatement de surface"},"content":{"rendered":"<h1 class=\"epArticleTitre\">EXPIRIS, le bureau d&rsquo;\u00e9tudes qui optimise vos rev\u00eatements techniques<\/h1>\n<div class=\"article-full__infos-topics\">Usine Nouvelle, novembre 2024<\/div>\n<p>https:\/\/www.gaches.com\/wp-content\/uploads\/2024\/02\/Usine-n-ouvelle-Expiris-pdf.jpg<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Onze experts staan voor u klaar<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Tel: +33 5 61 44 67 67\u00a0<\/span><\/p>\n<p>InformatieverzoekOffert aanvraag<\/p>","protected":false},"excerpt":{"rendered":"<p>EXPIRIS, le bureau d&rsquo;\u00e9tudes qui optimise vos rev\u00eatements techniques Usine Nouvelle, novembre 2024 https:\/\/www.gaches.com\/wp-content\/uploads\/2024\/02\/Usine-n-ouvelle-Expiris-pdf.jpg Nos experts sont \u00e0 votre \u00e9coute Tel: +33 5 61 44 67 67\u00a0 Demande d&rsquo;informationDemande de devis<\/p>","protected":false},"author":8,"featured_media":14796,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[20,34],"tags":[],"class_list":["post-17430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-laboratoire"],"_links":{"self":[{"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/posts\/17430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/comments?post=17430"}],"version-history":[{"count":0,"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/posts\/17430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/media\/14796"}],"wp:attachment":[{"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/media?parent=17430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/categories?post=17430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaches.com\/nl\/wp-json\/wp\/v2\/tags?post=17430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}