{"id":17653,"date":"2024-07-26T08:58:43","date_gmt":"2024-07-26T06:58:43","guid":{"rendered":"https:\/\/www.gaches.com\/?p=17653"},"modified":"2024-07-26T08:58:43","modified_gmt":"2024-07-26T06:58:43","slug":"limpact-de-la-qualite-et-la-presence-de-calcaire-dans-leau","status":"publish","type":"post","link":"https:\/\/www.gaches.com\/de\/limpact-de-la-qualite-et-la-presence-de-calcaire-dans-leau\/","title":{"rendered":"L&rsquo;impact de la qualit\u00e9 et la pr\u00e9sence de calcaire dans l&rsquo;eau"},"content":{"rendered":"<h1 class=\"sc-AxirZ sc-1ohdft1-0 leQiFa\">Le calcaire, un adversaire \u00e0 mieux conna\u00eetre pour pouvoir le combattre !<\/h1>\n<div class=\"sc-AxjAm xiy60q-0 kRkoFW\">\n<div class=\"sc-1mpwnru-0 dOIcua\">\n<div class=\"sc-1r87fjh-0 cxuwWh post-paywall\" data-testid=\"post-description\">\n<p>Le TH : Titre Hydrotim\u00e9trique, d\u00e9signe la duret\u00e9 de l&rsquo;eau. Cet indicateur exprime la teneur en sels de calcium et de magn\u00e9sium (composants du calcaire) dans l&rsquo;eau. Le TH s\u2019exprime en degr\u00e9s fran\u00e7ais (\u00b0f) ou en ppm. 1\u00b0f = 10 mg\/L = 10 ppm = 10 g \/m3 de carbonate de calcium. Une eau dure (TH \u00e9lev\u00e9) aura une forte concentration d\u2019ions Calcium et Magn\u00e9sium.<\/p>\n<p><strong>Si la duret\u00e9 de l&rsquo;eau :<\/strong><\/p>\n<ul>\n<li>d\u00e9passe 40\u00b0f, elle est consid\u00e9r\u00e9e comme tr\u00e8s dure,<\/li>\n<li>entre 30 et 40\u00b0f elle est consid\u00e9r\u00e9e dure,<\/li>\n<li>entre 15 et 30\u00b0f elle est consid\u00e9r\u00e9e plut\u00f4t dure,<\/li>\n<li>en dessous de 15\u00b0f l\u2019eau est consid\u00e9r\u00e9e comme douce.<\/li>\n<\/ul>\n<p>Le calcaire n&rsquo;est pas dangereux pour la sant\u00e9. N\u00e9anmoins il a tendance \u00e0 dess\u00e9cher la peau (il se d\u00e9pose sur la peau sous forme de petits cristaux, qui vont venir absorber l&rsquo;hydratation naturelle de l&rsquo;\u00e9piderme) et peut provoquer picotements et irritations.<\/p>\n<p>Par ailleurs, le calcaire est \u00e0 l&rsquo;origine du tarte, responsable de l\u2019entartrage :<\/p>\n<ul>\n<li>des \u00e9quipements : syst\u00e8mes de filtration et de traitement, pompes \u00e0 chaleur, pi\u00e8ces \u00e0 sceller, \u2026<\/li>\n<li>des rev\u00eatements des bassins (taches de couleur claires, du blanc aux gris, et pouvant \u00eatre color\u00e9es en pr\u00e9sence de m\u00e9taux : couleur orang\u00e9e en pr\u00e9sence de fer, \u2026) : au-del\u00e0 d\u2019un aspect esth\u00e9tique disgracieux le tartre sera un support pour aider les algues \u00e0 se d\u00e9velopper,<\/li>\n<li>des canalisations qui, au-del\u00e0 des risques de bouchons souvent irr\u00e9versibles, favorisera l\u2019accroche et la formation de biofilm<\/li>\n<li>des masses filtrantes cr\u00e9ant ainsi des chemins pr\u00e9f\u00e9rentiels de filtration,<\/li>\n<\/ul>\n<p>Vous trouverez la duret\u00e9 de l\u2019eau distribu\u00e9e dans votre r\u00e9seau sur votre facture annuelle d\u2019eau. Votre piscinier conseil peut aussi l\u2019analyser. Ci-apr\u00e8s vous trouverez une carte avec la duret\u00e9 moyenne par d\u00e9partement (attention il peut y avoir de grosses diff\u00e9rences de TH dans un m\u00eame d\u00e9partement).<\/p>\n<p>Au-del\u00e0 du calcium et du magn\u00e9sium pr\u00e9sents dans l\u2019eau de remplissage de votre piscine, l\u2019utilisation de certains produits chimiques peut amplifier la probl\u00e9matique : ainsi, l\u2019hypochlorite de calcium (chlore solide sans stabilisant) lib\u00e8rera du calcium qui va ainsi augmenter la duret\u00e9 de l\u2019eau de la piscine : \u00e0 chaque utilisation d\u2019hypochlorite de calcium (sous forme de \u00ab sticks \u00bb, de granul\u00e9s, de poudre, \u2026) la concentration en ions calcium, et donc le TH, va augmenter.<\/p>\n<p>La duret\u00e9 de l\u2019eau de remplissage d\u2019une piscine doit donc influencer le choix de la gamme de produits de traitement de l\u2019eau : en effet les diff\u00e9rentes qualit\u00e9s d\u2019eau pr\u00e9sentes en France ne permettent pas d\u2019utiliser indiff\u00e9remment n\u2019importe quel d\u00e9sinfectant que l\u2019on se trouve dans Le Puy de D\u00f4me ou dans l\u2019H\u00e9rault.<\/p>\n<p>L\u2019apport de Calcium gr\u00e2ce \u00e0 un traitement \u00e0 l\u2019hypochlorite de calcium sera b\u00e9n\u00e9fique dans les zones o\u00f9 l\u2019eau est douce (l\u2019eau sera moins agressive pour les \u00e9quipements et rev\u00eatements de la piscine) mais \u00e0 contrario cet apport sera probl\u00e9matique dans les zones o\u00f9 l\u2019eau est dure ou tr\u00e8s dure.<\/p>\n<p>Ainsi nous estimons qu\u2019un traitement sur une saison (avril \u2013 septembre) avec de l\u2019hypochlorite de calcium engendre une augmentation de plus de 20\u00b0f (1 stick de 300 gr par semaine pour 30 m3 et 3 chlorations choc avec de l\u2019hypochlorite de calcium en poudre ou granul\u00e9s) !<\/p>\n<p>Par cons\u00e9quent, nous pouvons nous retrouver avec des probl\u00e9matiques li\u00e9es au tartre m\u00eame dans des zones o\u00f9 l\u2019eau du r\u00e9seau est douce.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>https:\/\/www.gaches.com\/wp-content\/uploads\/2024\/07\/Capture.png<\/p>\n<p>Notons que l\u2019entartrage est favoris\u00e9 par un pH \u00e9lev\u00e9, ou tout au moins par un pH sup\u00e9rieur au pH d\u2019\u00e9quilibre de l\u2019eau. Certains traitements chimiques engendrent naturellement une augmentation du pH et il est donc pr\u00e9conis\u00e9 d\u2019installer une r\u00e9gulation automatique de pH pour compenser cette augmentation permanente li\u00e9e du pH dans le cas de traitements \u00e0 l\u2019hypochlorite de calcium (chlore dit \u00ab non stabilis\u00e9 \u00bb), \u00e0 l\u2019hypochlorite de sodium (chlore liquide \/ javel) ou \u00e0 l\u2019\u00e9lectrolyse du sel.<\/p>\n<p>L\u2019utilisation d\u2019eau de pluie pour les remises \u00e0 niveau du bassin peut \u00eatre b\u00e9n\u00e9fique dans le cas ou la duret\u00e9 de l\u2019eau du bassin est \u00e9lev\u00e9e (eau du r\u00e9seau calcaire et\/ou utilisation d\u2019hypochlorite de calcium). En effet l\u2019eau de pluie est tr\u00e8s peu min\u00e9ralis\u00e9e (peu charg\u00e9e en min\u00e9raux et donc en calcium) et permettra donc de diluer le calcium des eaux dures. L\u2019eau de pluie \u00e9tant g\u00e9n\u00e9ralement acide et d\u00e9min\u00e9ralis\u00e9e, si un r\u00e9servoir d\u2019eau est utilis\u00e9 pour remplir int\u00e9gralement sa piscine, il faudra prendre quelques pr\u00e9cautions : remonter le pH (avec du pH+), l\u2019alcalinit\u00e9 (avec du TAC+) voire la duret\u00e9 (avec du TH+). Enfin, pour cl\u00f4turer cette fiche concernant le calcaire, certaines mati\u00e8res actives de produits de traitement de l\u2019eau sont totalement inefficaces dans les eaux dures et tr\u00e8s dures : nous pouvons notamment citer les produits algicides et hivernages \u00e0 base de benzalkonium.<\/p>\n<p>Au-del\u00e0 des conseils li\u00e9s au pH, dans les zones ou l\u2019eau est dure ou tr\u00e8s dure et afin de limiter les effets n\u00e9fastes du calcaire, nous pr\u00e9conisons l\u2019utilisation du GARO\u00aecalcaire au remplissage de la piscine ainsi qu\u2019apr\u00e8s chaque remise \u00e0 niveau.<\/p>\n<p>https:\/\/www.gaches.com\/wp-content\/uploads\/2024\/07\/Capture2.png<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Nos experts sont \u00e0 votre \u00e9coute<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Tel: +33 5 61 44 67 67\u00a0<\/span><\/p>\n<p>Demande d&rsquo;informationDemande de devis<\/p>","protected":false},"excerpt":{"rendered":"<p>Le calcaire, un adversaire \u00e0 mieux conna\u00eetre pour pouvoir le combattre ! Le TH : Titre Hydrotim\u00e9trique, d\u00e9signe la duret\u00e9 de l&rsquo;eau. Cet indicateur exprime la teneur en sels de calcium et de magn\u00e9sium (composants du calcaire) dans l&rsquo;eau. Le TH s\u2019exprime en degr\u00e9s fran\u00e7ais (\u00b0f) ou en ppm. 1\u00b0f = 10 mg\/L = 10 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":17654,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1,26],"tags":[],"class_list":["post-17653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-piscine-piscine"],"_links":{"self":[{"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/posts\/17653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/comments?post=17653"}],"version-history":[{"count":0,"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/posts\/17653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/media\/17654"}],"wp:attachment":[{"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/media?parent=17653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/categories?post=17653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gaches.com\/de\/wp-json\/wp\/v2\/tags?post=17653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}